{"id":8141,"date":"2026-02-19T16:46:36","date_gmt":"2026-02-19T15:46:36","guid":{"rendered":"https:\/\/pangea.poggiomori.com\/azienda-agricola-sarteano-poggiomori\/"},"modified":"2026-04-23T17:42:34","modified_gmt":"2026-04-23T15:42:34","slug":"tuscany-winery-poggiomori","status":"publish","type":"page","link":"https:\/\/poggiomori.com\/en\/tuscany-winery-poggiomori\/","title":{"rendered":"Home Cantina"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8141\" class=\"elementor elementor-8141 elementor-7681\">\r\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb2f809 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"fb2f809\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04a413c\" data-id=\"04a413c\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-832176c elementor-widget elementor-widget-video\" data-id=\"832176c\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<style>\/*! elementor - v3.13.3 - 28-05-2023 *\/\r\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;left:0;width:100%;height:100%;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\r\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2026\/04\/home-vino-pm.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlsList=\"nodownload\"><\/video>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2db4811 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"2db4811\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c34df5\" data-id=\"5c34df5\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d4a361 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9d4a361\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<style>\/*! elementor - v3.13.3 - 28-05-2023 *\/\r\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\r\n\t\t\t<span class=\"elementor-divider-separator\">\r\n\t\t\t\t\t\t<\/span>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03ba02c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"03ba02c\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-db9b893\" data-id=\"db9b893\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-972a149\" data-id=\"972a149\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d954e12 elementor-widget elementor-widget-image\" data-id=\"d954e12\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<style>\/*! elementor - v3.13.3 - 28-05-2023 *\/\r\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/elementor\/thumbs\/cropped-logo-vite-1-112x112-1-rnaxay9f8kj1rid0w6ogf3zxjpzmk8ig5a0ec5lhc0.png\" title=\"cropped-logo-vite-1-112&#215;112\" alt=\"cropped-logo-vite-1-112x112\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4771481\" data-id=\"4771481\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-745dc1d elementor-widget elementor-widget-image\" data-id=\"745dc1d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/elementor\/thumbs\/fivi-rnaxay9f8kj1rid0w6ogf3zxjpzmk8ig5a0ec5lhc0.webp\" title=\"fivi\" alt=\"fivi\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1ec4465\" data-id=\"1ec4465\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fff37a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"fff37a5\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0274754\" data-id=\"0274754\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-876f08f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"876f08f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<div class=\"elementor-divider\">\r\n\t\t\t<span class=\"elementor-divider-separator\">\r\n\t\t\t\t\t\t<\/span>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a2b9c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"6a2b9c2\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e8be11\" data-id=\"7e8be11\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95c114b wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"95c114b\" data-element_type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\r\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\r\n\r\n\t\t\t\t\t\t<a class=\"wpr-promo-box-link\" href=\"https:\/\/poggiomori.com\/en\/winery-poggiomori-siena-sarteano\/\"><\/a>\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\r\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/06\/poggiomorinbotte.jpg);\"><\/div>\r\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t<div class=\"wpr-promo-box-content\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Winery<\/span><\/h3>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c28de4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"4c28de4\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f52f389\" data-id=\"f52f389\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89c55e6 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"89c55e6\" data-element_type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\r\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\r\n\r\n\t\t\t\t\t\t<a class=\"wpr-promo-box-link\" href=\"https:\/\/poggiomori.com\/en\/tuscan-wines\/\"><\/a>\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\r\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/poggiomori.com\/wp-content\/uploads\/2026\/03\/calici-2.png);\"><\/div>\r\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t<div class=\"wpr-promo-box-content\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Wines<\/span><\/h3>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b06f70 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"3b06f70\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ff8a23\" data-id=\"2ff8a23\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-403b80a wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"403b80a\" data-element_type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\r\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\r\n\r\n\t\t\t\t\t\t<a class=\"wpr-promo-box-link\" href=\"https:\/\/poggiomori.com\/en\/esperienze-cantina\/\"><\/a>\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\r\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/poggiomori.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-31-mar-2026-10_58_14.png);\"><\/div>\r\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t<div class=\"wpr-promo-box-content\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Experiences<\/span><\/h3>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca2f260 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"ca2f260\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a0bdd4\" data-id=\"0a0bdd4\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10941cf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"10941cf\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<div class=\"elementor-divider\">\r\n\t\t\t<span class=\"elementor-divider-separator\">\r\n\t\t\t\t\t\t<\/span>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98aabac elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"98aabac\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5e0356\" data-id=\"b5e0356\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d71badf elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"d71badf\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5f79947\" data-id=\"5f79947\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88f72c0 elementor-widget elementor-widget-heading\" data-id=\"88f72c0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<style>\/*! elementor - v3.13.3 - 28-05-2023 *\/\r\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h4 class=\"elementor-heading-title elementor-size-default\">News  <\/h4>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-33427dc elementor-widget elementor-widget-news_slider\" data-id=\"33427dc\" data-element_type=\"widget\" data-widget_type=\"news_slider.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t            <div class=\"news-slider-container\">\n                <div class=\"news-slider swiper-container\">\n                    <div class=\"swiper-wrapper\">\n                                                        <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/news-agriturismo-3\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/05\/Screenshot-2026-04-23-alle-17.01.30.png\" alt=\"It is a territory to discover.\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">It is a territory to discover.<\/h3>\n                                <\/div>\n                                                <\/div>\n                    <div class=\"swiper-button-next custom-nav-button\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\">\n                            <path d=\"M9 6l6 6-6 6\"\/>\n                        <\/svg>\n                    <\/div>\n                    <div class=\"swiper-button-prev custom-nav-button\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\">\n                            <path d=\"M15 6l-6 6 6 6\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/div>\n            <\/div>\n\n\n            <script>\n            jQuery(document).ready(function($) {\n                new Swiper('.news-slider', {\n                    navigation: {\n                        nextEl: '.custom-nav-button.swiper-button-next',\n                        prevEl: '.custom-nav-button.swiper-button-prev',\n                    },\n                    loop: true,\n                });\n            });\n            <\/script>\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4bb43be\" data-id=\"4bb43be\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bb2348 elementor-widget elementor-widget-heading\" data-id=\"3bb2348\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Gallery<\/h4>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-7e7b521 elementor-widget elementor-widget-image\" data-id=\"7e7b521\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/poggiomori.com\/gallery-2\/\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/elementor\/thumbs\/Schermata-2026-03-16-alle-17.01.30-rnaxay9mjp979mm8nkbfk65e9maa7pxq6zlj8j40je.png\" title=\"Schermata 2026-03-16 alle 17.01.30\" alt=\"Schermata 2026-03-16 alle 17.01.30\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a5d59dc\" data-id=\"a5d59dc\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-214765f elementor-widget elementor-widget-heading\" data-id=\"214765f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Reviews<\/h4>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-4646d58 elementor-widget elementor-widget-news_slider\" data-id=\"4646d58\" data-element_type=\"widget\" data-widget_type=\"news_slider.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t            <div class=\"news-slider-container\">\n                <div class=\"news-slider swiper-container\">\n                    <div class=\"swiper-wrapper\">\n                                                        <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/james-suckling-com-6\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/JAMES-SUCKLING-SERTORIUS-2019.jpg\" alt=\"James Suckling.com\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">James Suckling.com<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/james-suckling-com-5\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/JAMES-SUCKLING-boreo21jpg.jpg\" alt=\"James Suckling.com\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">James Suckling.com<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/wineenthusiast\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/08\/enthusiast-bludivigna.jpg\" alt=\"WineEnthusiast\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">WineEnthusiast<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/wineenthusiast_cb\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/08\/wineEnt-capriolo20.jpg\" alt=\"WineEnthusiast\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">WineEnthusiast<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/concours-mondiale-bruxelles-2\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/06\/medaillesertorius.jpg\" alt=\"Concours Mondiale Bruxelles\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Concours Mondiale Bruxelles<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/concours-mondiale-bruxelles\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/06\/medailleboreo.jpg\" alt=\"Concours Mondiale Bruxelles\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Concours Mondiale Bruxelles<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/falstaff\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/Chianti-riserva-2019-FALSTAFF.jpg\" alt=\"Falstaff\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Falstaff<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/decanter-2\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/Decanter-World-Blu-Di-Vigna-2019.jpg\" alt=\"Decanter\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Decanter<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/decanter\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/Decanter-World-wine-Award-Poggio-Mori-2019.jpg\" alt=\"Decanter\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Decanter<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/winescritic-com\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/Sertorius-2018-Wines-Critic.jpg\" alt=\"Winescritic.com\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Winescritic.com<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/guida-bio-4\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/GUIDA-BIO-Bludivigna-2019.jpg\" alt=\"Guida Bio\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Guida Bio<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/guida-bio-3\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/GUIDA-BIO-Il-Capriolo-Bianco-2020.jpg\" alt=\"Guida Bio\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Guida Bio<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/guida-bio-2\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/05\/GUIDA-BIO-poggiomori.jpg\" alt=\"Guida Bio\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Guida Bio<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/guida-bio\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/GUIDA-BIO-Sertorius-2018.jpg\" alt=\"Guida Bio\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">Guida Bio<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/james-suckling-com-4\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/JAMES-SUCKLING-BOREO-2020.jpg\" alt=\"James Suckling.com\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">James Suckling.com<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/james-suckling-com-3\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/JAMES-SUCKLING-IL-CAPRIOLO-BIANCO-2020.jpg\" alt=\"James Suckling.com\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">James Suckling.com<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/james-suckling-com-2\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/JAMES-SUCKLING-SERTORIUS-2017.jpg\" alt=\"James Suckling.com\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">James Suckling.com<\/h3>\n                                <\/div>\n                                                            <div class=\"swiper-slide\">\n                                    <a href=\"https:\/\/poggiomori.com\/en\/james-suckling-com\/\" class=\"slide-link\">\n                                        <div class=\"slide-image-container\" style=\"background-color: #FFFFFF\">\n                                            <img decoding=\"async\" src=\"https:\/\/poggiomori.com\/wp-content\/uploads\/2023\/12\/JAMES-SUCKLING-SERTORIUS-2018.jpg\" alt=\"James Suckling.com\" \/>                                            \n                                        <\/div>\n                                    <\/a>\n                                    <h3 class=\"post-title-container\">James Suckling.com<\/h3>\n                                <\/div>\n                                                <\/div>\n                    <div class=\"swiper-button-next custom-nav-button\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\">\n                            <path d=\"M9 6l6 6-6 6\"\/>\n                        <\/svg>\n                    <\/div>\n                    <div class=\"swiper-button-prev custom-nav-button\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\">\n                            <path d=\"M15 6l-6 6 6 6\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/div>\n            <\/div>\n\n\n            <script>\n            jQuery(document).ready(function($) {\n                new Swiper('.news-slider', {\n                    navigation: {\n                        nextEl: '.custom-nav-button.swiper-button-next',\n                        prevEl: '.custom-nav-button.swiper-button-prev',\n                    },\n                    loop: true,\n                });\n            });\n            <\/script>\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f94549 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"0f94549\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c8579f7\" data-id=\"c8579f7\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86f14e8 elementor-widget elementor-widget-spacer\" data-id=\"86f14e8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<style>\/*! elementor - v3.13.3 - 28-05-2023 *\/\r\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>https:\/\/pangea.poggiomori.com\/wp-content\/uploads\/2026\/04\/home-vino-pm.mp4 Winery Wines Experiences News PoggioMori un territorio da riscoprire Gallery Reviews James Suckling.com James Suckling.com James Suckling.com James Suckling.com WineEnthusiast WineEnthusiast Concours Mondiale Bruxelles Concours Mondiale Bruxelles Falstaff Decanter Decanter Winescritic.com Guida Bio Guida Bio Guida Bio Guida Bio James Suckling.com James Suckling.com<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"_links":{"self":[{"href":"https:\/\/poggiomori.com\/en\/wp-json\/wp\/v2\/pages\/8141"}],"collection":[{"href":"https:\/\/poggiomori.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/poggiomori.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/poggiomori.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/poggiomori.com\/en\/wp-json\/wp\/v2\/comments?post=8141"}],"version-history":[{"count":67,"href":"https:\/\/poggiomori.com\/en\/wp-json\/wp\/v2\/pages\/8141\/revisions"}],"predecessor-version":[{"id":11020,"href":"https:\/\/poggiomori.com\/en\/wp-json\/wp\/v2\/pages\/8141\/revisions\/11020"}],"wp:attachment":[{"href":"https:\/\/poggiomori.com\/en\/wp-json\/wp\/v2\/media?parent=8141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}